{"id":293,"count":295,"description":"","link":"https:\/\/doctor-property.co.th\/th\/property-features\/furnishing-options-th\/","name":"\u0e21\u0e35\u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e47\u0e08\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c","slug":"furnishing-options-th","taxonomy":"property-features","parent":0,"meta":[],"acf":{"meine-infoseite-icon_type":false,"meine-infoseite-icon-media":"","meine-infoseite-icon":""},"_links":{"self":[{"href":"https:\/\/doctor-property.co.th\/th\/wp-json\/wp\/v2\/property-features\/293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/doctor-property.co.th\/th\/wp-json\/wp\/v2\/property-features"}],"about":[{"href":"https:\/\/doctor-property.co.th\/th\/wp-json\/wp\/v2\/taxonomies\/property-features"}],"wp:post_type":[{"href":"https:\/\/doctor-property.co.th\/th\/wp-json\/wp\/v2\/property?property-features=293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}